{"id":218383,"date":"2025-04-29T14:16:41","date_gmt":"2025-04-29T11:16:41","guid":{"rendered":"https:\/\/walltopia.com\/products\/sem%20categoria\/espiral-de-escalada-de-nuvens\/"},"modified":"2026-01-22T14:14:48","modified_gmt":"2026-01-22T11:14:48","slug":"espiral-de-escalada-de-nuvens","status":"publish","type":"product","link":"https:\/\/walltopia.com\/pt-br\/product\/escalada-na-nuvem\/espiral-de-escalada-de-nuvens\/","title":{"rendered":"Espiral de escalada de nuvens"},"content":{"rendered":"<p>Este produto est\u00e1 dispon\u00edvel nas seguintes combina\u00e7\u00f5es de cores:<\/p>\n<h4>Floresta<\/h4>\n<div class=\"pantone-grid\">\n<div class=\"pantone-card p-161-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">7737 C<\/div>\n<\/div><\/div>\n<div class=\"pantone-card p-021-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">021 C<\/div>\n<\/div><\/div>\n<div class=\"pantone-card p-1375-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">1375 C<\/div>\n<\/div><\/div>\n<div class=\"pantone-card p-7741-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">7741 C<\/div>\n<\/div><\/div>\n<div class=\"pantone-card p-359-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">359 C<\/div>\n<\/div><\/div>\n<\/div>\n<h4>Verde bolha<\/h4>\n<div class=\"pantone-grid\">\n<div class=\"pantone-card p-7718-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">7718 C<\/div>\n<\/div><\/div>\n<div class=\"pantone-card p-11-0601-tpx\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">11-0601 TPX<\/div>\n<\/div><\/div>\n<div class=\"pantone-card p-7472-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">7472C<\/div>\n<\/div><\/div>\n<div class=\"pantone-card p-1777-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">1777C<\/div>\n<\/div><\/div>\n<div class=\"pantone-card p-1495-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">1495C<\/div>\n<\/div><\/div>\n<\/div>\n<h4>Rosa bolha<\/h4>\n<div class=\"pantone-grid\">\n<div class=\"pantone-card p-182-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">182 C<\/div>\n<\/div><\/div>\n<div class=\"pantone-card p-11-0601-tpx\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">11-0601 TPX<\/div>\n<\/div><\/div>\n<div class=\"pantone-card p-7718-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">7718C<\/div>\n<\/div><\/div>\n<div class=\"pantone-card p-7472-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">7472C<\/div>\n<\/div><\/div>\n<div class=\"pantone-card p-1777-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">1777C<\/div>\n<\/div><\/div>\n<div class=\"pantone-card p-1495-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">1495C<\/div>\n<\/div><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"Essa torre girat\u00f3ria de divers\u00e3o leva as crian\u00e7as a uma aventura ascendente ao longo de um caminho em espiral de discos suspensos. A Spiral incentiva o movimento circular, a coordena\u00e7\u00e3o e o movimento ininterrupto com uma subida suave e r\u00edtmica. ","protected":false},"featured_media":172428,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"product_brand":[],"product_cat":[7969],"product_tag":[],"class_list":["post-218383","product","type-product","status-publish","has-post-thumbnail","product_cat-escalada-na-nuvem","first","onbackorder","shipping-taxable","purchasable","product-type-variable"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Espiral de escalada de nuvens | Walltopia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/pt-br\/product\/escalada-na-nuvem\/espiral-de-escalada-de-nuvens\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Espiral de escalada de nuvens\" \/>\n<meta property=\"og:description\" content=\"Essa torre girat\u00f3ria de divers\u00e3o leva as crian\u00e7as a uma aventura ascendente ao longo de um caminho em espiral de discos suspensos. A Spiral incentiva o movimento circular, a coordena\u00e7\u00e3o e o movimento ininterrupto com uma subida suave e r\u00edtmica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/pt-br\/product\/escalada-na-nuvem\/espiral-de-escalada-de-nuvens\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-22T11:14:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20251002160802\/cloud-climb-spiral-forest-02-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/product\\\/escalada-na-nuvem\\\/espiral-de-escalada-de-nuvens\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/product\\\/escalada-na-nuvem\\\/espiral-de-escalada-de-nuvens\\\/\",\"name\":\"Espiral de escalada de nuvens | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/product\\\/escalada-na-nuvem\\\/espiral-de-escalada-de-nuvens\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/product\\\/escalada-na-nuvem\\\/espiral-de-escalada-de-nuvens\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20251002160802\\\/cloud-climb-spiral-forest-02-1-scaled.jpg\",\"datePublished\":\"2025-04-29T11:16:41+00:00\",\"dateModified\":\"2026-01-22T11:14:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/product\\\/escalada-na-nuvem\\\/espiral-de-escalada-de-nuvens\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/product\\\/escalada-na-nuvem\\\/espiral-de-escalada-de-nuvens\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/product\\\/escalada-na-nuvem\\\/espiral-de-escalada-de-nuvens\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20251002160802\\\/cloud-climb-spiral-forest-02-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20251002160802\\\/cloud-climb-spiral-forest-02-1-scaled.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/product\\\/escalada-na-nuvem\\\/espiral-de-escalada-de-nuvens\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/inicio-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Loja\",\"item\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/loja\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Espiral de escalada de nuvens\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Espiral de escalada de nuvens | Walltopia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/pt-br\/product\/escalada-na-nuvem\/espiral-de-escalada-de-nuvens\/","og_locale":"pt_BR","og_type":"article","og_title":"Espiral de escalada de nuvens","og_description":"Essa torre girat\u00f3ria de divers\u00e3o leva as crian\u00e7as a uma aventura ascendente ao longo de um caminho em espiral de discos suspensos. A Spiral incentiva o movimento circular, a coordena\u00e7\u00e3o e o movimento ininterrupto com uma subida suave e r\u00edtmica.","og_url":"https:\/\/walltopia.com\/pt-br\/product\/escalada-na-nuvem\/espiral-de-escalada-de-nuvens\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_modified_time":"2026-01-22T11:14:48+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20251002160802\/cloud-climb-spiral-forest-02-1-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/walltopia.com\/pt-br\/product\/escalada-na-nuvem\/espiral-de-escalada-de-nuvens\/","url":"https:\/\/walltopia.com\/pt-br\/product\/escalada-na-nuvem\/espiral-de-escalada-de-nuvens\/","name":"Espiral de escalada de nuvens | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/pt-br\/product\/escalada-na-nuvem\/espiral-de-escalada-de-nuvens\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/pt-br\/product\/escalada-na-nuvem\/espiral-de-escalada-de-nuvens\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20251002160802\/cloud-climb-spiral-forest-02-1-scaled.jpg","datePublished":"2025-04-29T11:16:41+00:00","dateModified":"2026-01-22T11:14:48+00:00","breadcrumb":{"@id":"https:\/\/walltopia.com\/pt-br\/product\/escalada-na-nuvem\/espiral-de-escalada-de-nuvens\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/pt-br\/product\/escalada-na-nuvem\/espiral-de-escalada-de-nuvens\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/walltopia.com\/pt-br\/product\/escalada-na-nuvem\/espiral-de-escalada-de-nuvens\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20251002160802\/cloud-climb-spiral-forest-02-1-scaled.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20251002160802\/cloud-climb-spiral-forest-02-1-scaled.jpg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/pt-br\/product\/escalada-na-nuvem\/espiral-de-escalada-de-nuvens\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/pt-br\/inicio-pt\/"},{"@type":"ListItem","position":2,"name":"Loja","item":"https:\/\/walltopia.com\/pt-br\/loja\/"},{"@type":"ListItem","position":3,"name":"Espiral de escalada de nuvens"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/pt-br\/#website","url":"https:\/\/walltopia.com\/pt-br\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/pt-br\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/walltopia.com\/pt-br\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/product\/218383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/product\/218383\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/media\/172428"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/media?parent=218383"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/product_brand?post=218383"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/product_cat?post=218383"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/product_tag?post=218383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}