{"id":220221,"date":"2025-10-07T08:48:33","date_gmt":"2025-10-07T05:48:33","guid":{"rendered":"https:\/\/walltopia.com\/products\/sem%20categoria\/cogumelo-cloud-climb\/"},"modified":"2026-01-22T14:26:34","modified_gmt":"2026-01-22T11:26:34","slug":"cogumelo-cloud-climb","status":"publish","type":"product","link":"https:\/\/walltopia.com\/pt-br\/product\/escalada-na-nuvem\/cogumelo-cloud-climb\/","title":{"rendered":"Cogumelo Cloud Climb"},"content":{"rendered":"<p>Este produto est\u00e1 dispon\u00edvel nas seguintes combina\u00e7\u00f5es de cores:<\/p>\n<h4>P\u00f4r do sol<\/h4>\n<div class=\"pantone-grid\">\n<div class=\"pantone-card p-283-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">283 C<\/div><\/div><\/div>\n<div class=\"pantone-card p-1665-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">1665 C<\/div><\/div><\/div>\n<div class=\"pantone-card p-1495-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">1495 C<\/div><\/div><\/div>\n<div class=\"pantone-card p-1235-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">1235 C<\/div><\/div><\/div>\n<div class=\"pantone-card p-283-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">283 C<\/div><\/div><\/div>\n<div class=\"pantone-card p-308-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">308 C<\/div><\/div><\/div>\n<\/div>\n<h4>Lavanda<\/h4>\n<div class=\"pantone-grid\">\n<div class=\"pantone-card p-270-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">270 C<\/div><\/div><\/div>\n<div class=\"pantone-card p-2050-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">2050 C<\/div><\/div><\/div>\n<div class=\"pantone-card p-7443-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">7443 C<\/div><\/div><\/div>\n<div class=\"pantone-card p-250-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">250 C<\/div><\/div><\/div>\n<div class=\"pantone-card p-270-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">270 C<\/div><\/div><\/div>\n<div class=\"pantone-card p-7451-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">7451 C<\/div><\/div><\/div>\n<\/div>\n<h4>Floresta<\/h4>\n<div class=\"pantone-grid\">\n<div class=\"pantone-card p-635-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">635 C<\/div><\/div><\/div>\n<div class=\"pantone-card p-196-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">196 C<\/div><\/div><\/div>\n<div class=\"pantone-card p-635-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">635 C<\/div><\/div><\/div>\n<div class=\"pantone-card p-372-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">372 C<\/div><\/div><\/div>\n<div class=\"pantone-card p-7465-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">7465 C<\/div><\/div><\/div>\n<div class=\"pantone-card p-7473-c\">\n<div class=\"pantone-swatch\"><\/div>\n<div class=\"pantone-text\">\n<div class=\"pantone-brand\"><\/div>\n<div class=\"pantone-number\">7473 C<\/div><\/div><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"Com seu formato marcante e presen\u00e7a arrojada, o Mushroom \u00e9 uma pe\u00e7a central visual que chama a aten\u00e7\u00e3o instantaneamente. Projetado para se assemelhar a um cogumelo gigante, esse modelo convida as crian\u00e7as a uma emocionante escalada vertical que termina em um passeio emocionante pelo escorregador de a\u00e7o inoxid\u00e1vel embutido. Atraente e cheio de divers\u00e3o, o Mushroom transforma qualquer local em um destino.  \n\n<strong>*O pre\u00e7o listado para o modelo Mushroom inclui o slide.<\/strong>","protected":false},"featured_media":171776,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"product_brand":[],"product_cat":[7969],"product_tag":[],"class_list":["post-220221","product","type-product","status-publish","has-post-thumbnail","product_cat-escalada-na-nuvem","first","instock","shipping-taxable","purchasable","product-type-variable"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cogumelo Cloud Climb | Walltopia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/pt-br\/product\/escalada-na-nuvem\/cogumelo-cloud-climb\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cogumelo Cloud Climb\" \/>\n<meta property=\"og:description\" content=\"Com seu formato marcante e presen\u00e7a arrojada, o Mushroom \u00e9 uma pe\u00e7a central visual que chama a aten\u00e7\u00e3o instantaneamente. Projetado para se assemelhar a um cogumelo gigante, esse modelo convida as crian\u00e7as a uma emocionante escalada vertical que termina em um passeio emocionante pelo escorregador de a\u00e7o inoxid\u00e1vel embutido. Atraente e cheio de divers\u00e3o, o Mushroom transforma qualquer local em um destino.  *O pre\u00e7o listado para o modelo Mushroom inclui o slide.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/pt-br\/product\/escalada-na-nuvem\/cogumelo-cloud-climb\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-22T11:26:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250930094848\/cloud-climb-mushroom-forest-01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/product\\\/escalada-na-nuvem\\\/cogumelo-cloud-climb\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/product\\\/escalada-na-nuvem\\\/cogumelo-cloud-climb\\\/\",\"name\":\"Cogumelo Cloud Climb | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/product\\\/escalada-na-nuvem\\\/cogumelo-cloud-climb\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/product\\\/escalada-na-nuvem\\\/cogumelo-cloud-climb\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20250930094848\\\/cloud-climb-mushroom-forest-01.jpg\",\"datePublished\":\"2025-10-07T05:48:33+00:00\",\"dateModified\":\"2026-01-22T11:26:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/product\\\/escalada-na-nuvem\\\/cogumelo-cloud-climb\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/product\\\/escalada-na-nuvem\\\/cogumelo-cloud-climb\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/product\\\/escalada-na-nuvem\\\/cogumelo-cloud-climb\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20250930094848\\\/cloud-climb-mushroom-forest-01.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20250930094848\\\/cloud-climb-mushroom-forest-01.jpg\",\"width\":1920,\"height\":1280,\"caption\":\"Walltopia Cloud Climb Mushroom\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/product\\\/escalada-na-nuvem\\\/cogumelo-cloud-climb\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/inicio-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Loja\",\"item\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/loja\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cogumelo Cloud Climb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cogumelo Cloud Climb | Walltopia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/pt-br\/product\/escalada-na-nuvem\/cogumelo-cloud-climb\/","og_locale":"pt_BR","og_type":"article","og_title":"Cogumelo Cloud Climb","og_description":"Com seu formato marcante e presen\u00e7a arrojada, o Mushroom \u00e9 uma pe\u00e7a central visual que chama a aten\u00e7\u00e3o instantaneamente. Projetado para se assemelhar a um cogumelo gigante, esse modelo convida as crian\u00e7as a uma emocionante escalada vertical que termina em um passeio emocionante pelo escorregador de a\u00e7o inoxid\u00e1vel embutido. Atraente e cheio de divers\u00e3o, o Mushroom transforma qualquer local em um destino.  *O pre\u00e7o listado para o modelo Mushroom inclui o slide.","og_url":"https:\/\/walltopia.com\/pt-br\/product\/escalada-na-nuvem\/cogumelo-cloud-climb\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_modified_time":"2026-01-22T11:26:34+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250930094848\/cloud-climb-mushroom-forest-01.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/walltopia.com\/pt-br\/product\/escalada-na-nuvem\/cogumelo-cloud-climb\/","url":"https:\/\/walltopia.com\/pt-br\/product\/escalada-na-nuvem\/cogumelo-cloud-climb\/","name":"Cogumelo Cloud Climb | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/pt-br\/product\/escalada-na-nuvem\/cogumelo-cloud-climb\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/pt-br\/product\/escalada-na-nuvem\/cogumelo-cloud-climb\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250930094848\/cloud-climb-mushroom-forest-01.jpg","datePublished":"2025-10-07T05:48:33+00:00","dateModified":"2026-01-22T11:26:34+00:00","breadcrumb":{"@id":"https:\/\/walltopia.com\/pt-br\/product\/escalada-na-nuvem\/cogumelo-cloud-climb\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/pt-br\/product\/escalada-na-nuvem\/cogumelo-cloud-climb\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/walltopia.com\/pt-br\/product\/escalada-na-nuvem\/cogumelo-cloud-climb\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250930094848\/cloud-climb-mushroom-forest-01.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250930094848\/cloud-climb-mushroom-forest-01.jpg","width":1920,"height":1280,"caption":"Walltopia Cloud Climb Mushroom"},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/pt-br\/product\/escalada-na-nuvem\/cogumelo-cloud-climb\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/pt-br\/inicio-pt\/"},{"@type":"ListItem","position":2,"name":"Loja","item":"https:\/\/walltopia.com\/pt-br\/loja\/"},{"@type":"ListItem","position":3,"name":"Cogumelo Cloud Climb"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/pt-br\/#website","url":"https:\/\/walltopia.com\/pt-br\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/pt-br\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/walltopia.com\/pt-br\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/product\/220221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/product\/220221\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/media\/171776"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/media?parent=220221"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/product_brand?post=220221"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/product_cat?post=220221"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/product_tag?post=220221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}