{"id":15938,"date":"2021-07-06T16:47:22","date_gmt":"2021-07-06T13:47:22","guid":{"rendered":"https:\/\/dev-three.agmastudio.com\/?post_type=wt_project&#038;p=15938"},"modified":"2023-05-22T14:35:53","modified_gmt":"2023-05-22T11:35:53","slug":"indoorwall-centers-alicante","status":"publish","type":"wt_project","link":"https:\/\/walltopia.com\/pt-br\/projects\/indoorwall-centers-alicante\/","title":{"rendered":"Indoorwall Centers: Alicante"},"content":{"rendered":"","protected":false},"featured_media":15941,"template":"","wt_project_category":[761],"class_list":["post-15938","wt_project","type-wt_project","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Indoorwall Centers: Alicante - Projects | Walltopia Climbing Walls<\/title>\n<meta name=\"description\" content=\"Indoorwall Centers: Alicante is a Full Service Climbing Gym with Rope Walls and Boulder Walls in Alicante, Spain.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/pt-br\/projects\/indoorwall-centers-alicante\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Indoorwall Centers: Alicante\" \/>\n<meta property=\"og:description\" content=\"Indoorwall Centers: Alicante is a Full Service Climbing Gym with Rope Walls and Boulder Walls in Alicante, Spain.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/pt-br\/projects\/indoorwall-centers-alicante\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-22T11:35:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231030101323\/CC3BF375-5DF9-478D-A1A1-C8A9719B3F33-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/projects\\\/indoorwall-centers-alicante\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/projects\\\/indoorwall-centers-alicante\\\/\",\"name\":\"Indoorwall Centers: Alicante - Projects | Walltopia Climbing Walls\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/projects\\\/indoorwall-centers-alicante\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/projects\\\/indoorwall-centers-alicante\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231030101323\\\/CC3BF375-5DF9-478D-A1A1-C8A9719B3F33-4.jpg\",\"datePublished\":\"2021-07-06T13:47:22+00:00\",\"dateModified\":\"2023-05-22T11:35:53+00:00\",\"description\":\"Indoorwall Centers: Alicante is a Full Service Climbing Gym with Rope Walls and Boulder Walls in Alicante, Spain.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/projects\\\/indoorwall-centers-alicante\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/projects\\\/indoorwall-centers-alicante\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/projects\\\/indoorwall-centers-alicante\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231030101323\\\/CC3BF375-5DF9-478D-A1A1-C8A9719B3F33-4.jpg\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20231030101323\\\/CC3BF375-5DF9-478D-A1A1-C8A9719B3F33-4.jpg\",\"width\":1200,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/projects\\\/indoorwall-centers-alicante\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/inicio-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projects\",\"item\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/projects\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Indoorwall Centers: Alicante\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Indoorwall Centers: Alicante - Projects | Walltopia Climbing Walls","description":"Indoorwall Centers: Alicante is a Full Service Climbing Gym with Rope Walls and Boulder Walls in Alicante, Spain.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/pt-br\/projects\/indoorwall-centers-alicante\/","og_locale":"pt_BR","og_type":"article","og_title":"Indoorwall Centers: Alicante","og_description":"Indoorwall Centers: Alicante is a Full Service Climbing Gym with Rope Walls and Boulder Walls in Alicante, Spain.","og_url":"https:\/\/walltopia.com\/pt-br\/projects\/indoorwall-centers-alicante\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_modified_time":"2023-05-22T11:35:53+00:00","og_image":[{"width":1200,"height":900,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231030101323\/CC3BF375-5DF9-478D-A1A1-C8A9719B3F33-4.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/walltopia.com\/pt-br\/projects\/indoorwall-centers-alicante\/","url":"https:\/\/walltopia.com\/pt-br\/projects\/indoorwall-centers-alicante\/","name":"Indoorwall Centers: Alicante - Projects | Walltopia Climbing Walls","isPartOf":{"@id":"https:\/\/walltopia.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/pt-br\/projects\/indoorwall-centers-alicante\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/pt-br\/projects\/indoorwall-centers-alicante\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231030101323\/CC3BF375-5DF9-478D-A1A1-C8A9719B3F33-4.jpg","datePublished":"2021-07-06T13:47:22+00:00","dateModified":"2023-05-22T11:35:53+00:00","description":"Indoorwall Centers: Alicante is a Full Service Climbing Gym with Rope Walls and Boulder Walls in Alicante, Spain.","breadcrumb":{"@id":"https:\/\/walltopia.com\/pt-br\/projects\/indoorwall-centers-alicante\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/pt-br\/projects\/indoorwall-centers-alicante\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/walltopia.com\/pt-br\/projects\/indoorwall-centers-alicante\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231030101323\/CC3BF375-5DF9-478D-A1A1-C8A9719B3F33-4.jpg","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231030101323\/CC3BF375-5DF9-478D-A1A1-C8A9719B3F33-4.jpg","width":1200,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/pt-br\/projects\/indoorwall-centers-alicante\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/pt-br\/inicio-pt\/"},{"@type":"ListItem","position":2,"name":"Projects","item":"https:\/\/walltopia.com\/pt-br\/projects\/"},{"@type":"ListItem","position":3,"name":"Indoorwall Centers: Alicante"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/pt-br\/#website","url":"https:\/\/walltopia.com\/pt-br\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/pt-br\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/walltopia.com\/pt-br\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/wt_project\/15938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/wt_project"}],"about":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/types\/wt_project"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/media\/15941"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/media?parent=15938"}],"wp:term":[{"taxonomy":"wt_project_category","embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/wt_project_category?post=15938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}