{"id":124910,"date":"2021-04-23T16:53:54","date_gmt":"2021-04-23T13:53:54","guid":{"rendered":"http:\/\/walltopia.com\/testimonials\/steven-brown\/"},"modified":"2021-04-23T16:53:54","modified_gmt":"2021-04-23T13:53:54","slug":"steven-brown","status":"publish","type":"wt_testimonial","link":"https:\/\/walltopia.com\/pt-br\/testimonials\/steven-brown\/","title":{"rendered":"Steven Brown"},"featured_media":0,"template":"","testimonial_category":[828],"class_list":["post-124910","wt_testimonial","type-wt_testimonial","status-publish","hentry","testimonial_category-climbing"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Steven Brown | Walltopia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/pt-br\/testimonials\/steven-brown\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Steven Brown\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/pt-br\/testimonials\/steven-brown\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/testimonials\\\/steven-brown\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/testimonials\\\/steven-brown\\\/\",\"name\":\"Steven Brown | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#website\"},\"datePublished\":\"2021-04-23T13:53:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/testimonials\\\/steven-brown\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/testimonials\\\/steven-brown\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/testimonials\\\/steven-brown\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/inicio-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Testimonials\",\"item\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/testimonials\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Steven Brown\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Steven Brown | Walltopia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/pt-br\/testimonials\/steven-brown\/","og_locale":"pt_BR","og_type":"article","og_title":"Steven Brown","og_url":"https:\/\/walltopia.com\/pt-br\/testimonials\/steven-brown\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/walltopia.com\/pt-br\/testimonials\/steven-brown\/","url":"https:\/\/walltopia.com\/pt-br\/testimonials\/steven-brown\/","name":"Steven Brown | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/pt-br\/#website"},"datePublished":"2021-04-23T13:53:54+00:00","breadcrumb":{"@id":"https:\/\/walltopia.com\/pt-br\/testimonials\/steven-brown\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/pt-br\/testimonials\/steven-brown\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/pt-br\/testimonials\/steven-brown\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/pt-br\/inicio-pt\/"},{"@type":"ListItem","position":2,"name":"Testimonials","item":"https:\/\/walltopia.com\/pt-br\/testimonials\/"},{"@type":"ListItem","position":3,"name":"Steven Brown"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/pt-br\/#website","url":"https:\/\/walltopia.com\/pt-br\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/pt-br\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/walltopia.com\/pt-br\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/wt_testimonial\/124910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/wt_testimonial"}],"about":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/types\/wt_testimonial"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/media?parent=124910"}],"wp:term":[{"taxonomy":"testimonial_category","embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/testimonial_category?post=124910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}