{"id":124424,"date":"2021-03-31T19:45:08","date_gmt":"2021-03-31T16:45:08","guid":{"rendered":"http:\/\/walltopia.com\/products\/quadros-de-treinamento\/"},"modified":"2026-01-28T11:24:14","modified_gmt":"2026-01-28T08:24:14","slug":"quadros-de-treinamento","status":"publish","type":"wt_wall_type","link":"https:\/\/walltopia.com\/pt-br\/products\/quadros-de-treinamento\/","title":{"rendered":"Quadros de treinamento"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row el_id=&#8221;Navega\u00e7\u00e3o de marcadores&#8221;][vc_column][vc_raw_html]PHVsIGNsYXNzPSJtYWluLXNpdGUtdGFicy1uYXZpZ2F0aW9uIGR5bmFtaWMtd2lkdGgtZWxlbWVudHMiPgo8bGkgY2xhc3M9InNpbmdsZS10YWItdGl0bGUgZHluYW1pYy13aWR0aC1lbGVtZW50Ij48YSBocmVmPSIjdHJhaW5pbmctYm9hcmRzIj5RdWFkcm9zIGRlIHRyZWluYW1lbnRvPC9hPjwvbGk+CjxsaSBjbGFzcz0ic2luZ2xlLXRhYi10aXRsZSBkeW5hbWljLXdpZHRoLWVsZW1lbnQiPjxhIGhyZWY9IiNmbGV4LWJvYXJkIj5QbGFjYSBmbGV4w612ZWw8L2E+PC9saT4KPGxpIGNsYXNzPSJzaW5nbGUtdGFiLXRpdGxlIGR5bmFtaWMtd2lkdGgtZWxlbWVudCI+PGEgaHJlZj0iI3Bvd2VyLWJveCI+Q2FpeGEgZGUgZm9yw6dhPC9hPjwvbGk+CjxsaSBjbGFzcz0ic2luZ2xlLXRhYi10aXRsZSBkeW5hbWljLXdpZHRoLWVsZW1lbnQiPjxhIGhyZWY9IiNmbG9vcmluZyI+UGlzb3M8L2E+PC9saT4KPGxpIGNsYXNzPSJzaW5nbGUtdGFiLXRpdGxlIGR5bmFtaWMtd2lkdGgtZWxlbWVudCI+PGEgaHJlZj0iI3Byb2plY3RzIj5Qcm9qZXRvczwvYT48L2xpPgo8bGkgY2xhc3M9InNpbmdsZS10YWItdGl0bGUgZHluYW1pYy13aWR0aC1lbGVtZW50Ij48YSBocmVmPSIjZG93bmxvYWRzIj5Eb3dubG9hZHM8L2E+PC9saT4KCjwvdWw+[\/vc_raw_html][\/vc_column][\/vc_row][vc_row el_id=&#8221;Conselhos de treinamento&#8221;][vc_column]<div class=\"info-block-container info-block shdw shdw margin-bottom-100\"><div class=\"content\"><h2>Kilter Board<\/h2><div class=\"full-width-container\"><\/p>\n<ul>\n<li>Overhang: Walltopia adjustable frame or a fixed angle as per client\u2019s request<\/li>\n<li>Standard holds sets: available for order through Walltopia at an additional charge.<\/li>\n<li>LED hardware: included in the price<\/li>\n<li>Climbing surface area: <strong>Kilter Board Commercial:<\/strong> 12x12ft (366x366cm) <strong>Kilter Board Half<\/strong>: 8x12 ft (244x366 cm) <em>Made to fit narrow spaces<\/em> <strong>Kilter Board Short:<\/strong> 7x10 ft (213x305 cm) <em>Made to fit shorter spaces<\/em><\/li>\n<\/ul>\n<p>\n<\/div><a href=\"http:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027223324\/Walltopia-Training-Boards-Brochure.pdf\" class=\"hover-effect-fast\" target=\"_blank\">Download Brochure<\/a><\/div><!-- .content --><div id=\"chocolat-parent\" class=\"slides-images-in-tab start-slick owl-carousel owl-theme\"><a class=\"chocolat-image\" href=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027223414\/KilterBoard-scaled.jpg\"><img decoding=\"async\" src=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027223414\/KilterBoard-800x600.jpg\" width=\"100%\" height=\"auto\" alt=\"\" \/><\/a><a class=\"chocolat-image\" href=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027223408\/KilterBoard2-scaled.jpg\"><img decoding=\"async\" src=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027223408\/KilterBoard2-800x600.jpg\" width=\"100%\" height=\"auto\" alt=\"\" \/><\/a><a class=\"chocolat-image\" href=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027223402\/KilterBoard3-scaled.jpg\"><img decoding=\"async\" src=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027223402\/KilterBoard3-800x600.jpg\" width=\"100%\" height=\"auto\" alt=\"\" \/><\/a><a class=\"chocolat-image\" href=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027223344\/training-boards2-scaled.jpg\"><img decoding=\"async\" src=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027223344\/training-boards2-800x600.jpg\" width=\"100%\" height=\"auto\" alt=\"\" \/><\/a><\/div><\/div><!-- .info-block-container --><div class=\"info-block-container info-block shdw shdw margin-bottom-100\"><div class=\"content\"><h2>Moon Board<\/h2><div class=\"full-width-container\"><\/p>\n<ul>\n<li>Overhang: 40\u00b0<\/li>\n<li>Standard holds sets: available for order through Walltopia at an additional charge<\/li>\n<li>LED hardware: available to order through Walltopia at an additional charge<\/li>\n<li>T-nut spacing: 20 x 20 cm<\/li>\n<li>Climbing surface area: 9.8 m2 (105.5 sq.ft)<\/li>\n<\/ul>\n<p>\n<\/div><a href=\"http:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027223324\/Walltopia-Training-Boards-Brochure.pdf\" class=\"hover-effect-fast\" target=\"_blank\">Download Brochure<\/a><\/div><!-- .content --><div id=\"chocolat-parent\" class=\"slides-images-in-tab start-slick owl-carousel owl-theme\"><a class=\"chocolat-image\" href=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027223356\/MoonBoard-scaled.jpg\"><img decoding=\"async\" src=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027223356\/MoonBoard-800x600.jpg\" width=\"100%\" height=\"auto\" alt=\"\" \/><\/a><a class=\"chocolat-image\" href=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027223351\/SAM_8043-19.jpg\"><img decoding=\"async\" src=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027223351\/SAM_8043-19-800x600.jpg\" width=\"100%\" height=\"auto\" alt=\"\" \/><\/a><\/div><\/div><!-- .info-block-container --><div class=\"info-block-container info-block shdw shdw margin-bottom-100\"><div class=\"content\"><h2>Tension Board<\/h2><div class=\"full-width-container\"><\/p>\n<ul>\n<li>Overhang: Walltopia adjustable frame or a fixed angle as per the client\u2019s request.<\/li>\n<li>Standard holds sets: available for order through Walltopia at an additional charge<\/li>\n<li>LED hardware: available to order through Walltopia at an additional charge<\/li>\n<li>T-nut spacing: 20 x 20 cm (optional 10 x 10 cm)<\/li>\n<li>Climbing surface area: <strong>Tension Board Classic:<\/strong> 9.6 m2 (103 sq.ft) <strong>Tension Board Short<\/strong>: 8 m2 (86 sq.ft) <em>Made to fit narrow spaces<\/em> <strong>Tension Board Shotr&amp;Narrow:<\/strong> 5.2 m2 (56 sq.ft) <em>Made to fit shorter spaces<\/em><\/li>\n<\/ul>\n<p>\n<\/div><a href=\"http:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027223324\/Walltopia-Training-Boards-Brochure.pdf\" class=\"hover-effect-fast\" target=\"_blank\">Download Brochure<\/a><\/div><!-- .content --><div id=\"chocolat-parent\" class=\"slides-images-in-tab start-slick owl-carousel owl-theme\"><a class=\"chocolat-image\" href=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027223341\/TensionBoard-scaled.jpg\"><img decoding=\"async\" src=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027223341\/TensionBoard-800x600.jpg\" width=\"100%\" height=\"auto\" alt=\"\" \/><\/a><a class=\"chocolat-image\" href=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027223337\/TensionBoard2-scaled.jpg\"><img decoding=\"async\" src=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027223337\/TensionBoard2-800x600.jpg\" width=\"100%\" height=\"auto\" alt=\"\" \/><\/a><a class=\"chocolat-image\" href=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027223334\/TensionBoard3-scaled.jpg\"><img decoding=\"async\" src=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027223334\/TensionBoard3-800x600.jpg\" width=\"100%\" height=\"auto\" alt=\"\" \/><\/a><a class=\"chocolat-image\" href=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027223326\/TensionBoard4-scaled.jpg\"><img decoding=\"async\" src=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027223326\/TensionBoard4-800x600.jpg\" width=\"100%\" height=\"auto\" alt=\"\" \/><\/a><\/div><\/div><!-- .info-block-container --><div class=\"info-block-container info-block shdw shdw margin-bottom-100\"><div class=\"content\"><h2>L-shape training zone<\/h2><div class=\"full-width-container\"><p>It\u2019s a common practice for climbing gyms to build training walls along building corners. We developed a signature design that can be taken as a template and adjusted based on the client\u2019s preference. One side of the unit is a 40\u00b0 overhanging wall (angle may vary upon request) with a size that can accommodate a commercial Kilter Board or a combination of two smaller boards such as Moon board, a full size Tension board, a full size Kilter board. The other side of the unit consists of standard campus wall with a width depending on the number of campus lines required.<\/p>\n<\/div><a href=\"http:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027223324\/Walltopia-Training-Boards-Brochure.pdf\" class=\"hover-effect-fast\" target=\"_blank\">Download Brochure<\/a><\/div><!-- .content --><div id=\"chocolat-parent\" class=\"image\"><a class=\"chocolat-image\" href=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027223319\/L-shape-training-area-scaled.jpg\"><img decoding=\"async\" src=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027223319\/L-shape-training-area-800x600.jpg\" width=\"100%\" height=\"auto\" alt=\"\" \/><\/a><\/div><\/div><!-- .info-block-container --><div class=\"info-block-container info-block shdw shdw margin-bottom-100\"><div class=\"content\"><h2>Campus Board<\/h2><div class=\"full-width-container\"><\/p>\n<ul>\n<li>Overhang: 15\u00b0<\/li>\n<li>Campus rungs count: 10<\/li>\n<li>Campus rungs width: 50 cm (20``)<\/li>\n<li>Surface area of a one-line campus board: 2.2 m2 (24 sq.ft)<\/li>\n<\/ul>\n<p>\n<\/div><a href=\"http:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027223324\/Walltopia-Training-Boards-Brochure.pdf\" class=\"hover-effect-fast\" target=\"_blank\">Download Brochure<\/a><\/div><!-- .content --><div id=\"chocolat-parent\" class=\"slides-images-in-tab start-slick owl-carousel owl-theme\"><a class=\"chocolat-image\" href=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027223237\/Campus-board-scaled.jpg\"><img decoding=\"async\" src=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027223237\/Campus-board-800x600.jpg\" width=\"100%\" height=\"auto\" alt=\"\" \/><\/a><a class=\"chocolat-image\" href=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027223243\/Campus-board2-scaled.jpg\"><img decoding=\"async\" src=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027223243\/Campus-board2-800x600.jpg\" width=\"100%\" height=\"auto\" alt=\"\" \/><\/a><\/div><\/div><!-- .info-block-container --><div class=\"info-block-container info-block shdw shdw margin-bottom-100\"><div class=\"content\"><h2>Adjustable Angle Wall<\/h2><div class=\"full-width-container\"><p>Most of the widely used training boards can be mounted on an angle-changing frame. This allows to modify the difficulty of the very same board setup by adjusting the inclination of the wall. We offer two variations of angle changing frame: hydraulic and electrical. The electric requires no maintenance as opposed to the hydraulic one which is the economy solution at the cost of daily oil and pressure level checks of the hydraulic system. Both variations are engineered to comply with the standards for loads of boulder wall at every angle of inclination they can be used. <\/p>\n<ul>\n<li>Overhang: 0\u00b0 to 70\u00b0<\/li>\n<li>Electrical system: No maintenance required<\/li>\n<li>Hydraulic system: Less expensive option; requires daily oil level and pressure checks<\/li>\n<li>Standards compliance: fully compliant with EN boulder wall standard for loads applied to every angle position.<\/li>\n<li>LED hardware: available to order through Walltopia at an additional charge<\/li>\n<li>T-nut spacing: 10 x 10 cm<\/li>\n<li>Climbing surface area: 9.8 m2 (105.5 sq.ft)<\/li>\n<\/ul>\n<p>\n<\/div><\/div><!-- .content --><div id=\"chocolat-parent\" class=\"slides-images-in-tab start-slick owl-carousel owl-theme\"><a class=\"chocolat-image\" href=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027223312\/Adjustable-angle-training-wall-scaled.jpg\"><img decoding=\"async\" src=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027223312\/Adjustable-angle-training-wall-800x600.jpg\" width=\"100%\" height=\"auto\" alt=\"\" \/><\/a><a class=\"chocolat-image\" href=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027223253\/Adjustable-angle-training-wall3-scaled.jpg\"><img decoding=\"async\" src=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027223253\/Adjustable-angle-training-wall3-800x600.jpg\" width=\"100%\" height=\"auto\" alt=\"\" \/><\/a><a class=\"chocolat-image\" href=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027223302\/Adjustable-angle-training-wall2-scaled.jpg\"><img decoding=\"async\" src=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027223302\/Adjustable-angle-training-wall2-800x600.jpg\" width=\"100%\" height=\"auto\" alt=\"\" \/><\/a><\/div><\/div><!-- .info-block-container -->[\/vc_column][\/vc_row][vc_row el_id=&#8221;Painel flex\u00edvel&#8221; css=&#8221;.vc_custom_1636998125139{margin-bottom: 100px !important;}&#8221;][vc_column el_class=&#8221;shdw margin-bottom-100&#8243;][vc_single_image image=&#8221;124455&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][vc_empty_space height=&#8221;50px&#8221;][vc_column_text css=&#8221;.vc_custom_1637056924293{padding-top: 50px !important;padding-right: 50px !important;padding-bottom: 50px !important;padding-left: 50px !important;}&#8221;]\n<p><strong>QUADRO FLEX\u00cdVEL WALLTOPIA: O MAIOR QUADRO DE TREINAMENTO QUE OCUPA MENOS ESPA\u00c7O<\/strong><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>A solu\u00e7\u00e3o definitiva de utiliza\u00e7\u00e3o de espa\u00e7o<\/li>\n<li>Diversas op\u00e7\u00f5es de treinamento<\/li>\n<li>Variedade de al\u00e7as<\/li>\n<li>F\u00e1cil de montar<\/li>\n<li>Perfeito para treinamento em casa e em \u00e1reas de treinamento em academias.<\/li>\n<\/ul>\n<p>A utiliza\u00e7\u00e3o do espa\u00e7o \u00e9 fundamental para a boa experi\u00eancia do cliente em uma academia de escalada. O espa\u00e7o para zonas de treinamento pode ser facilmente ignorado em favor de mais superf\u00edcie de escalada, mas \u00e9 fundamental para desenvolver a for\u00e7a e melhorar as habilidades de escalada. Por isso, criamos um quadro de treinamento que oferece excelente treinamento e ocupa pouco espa\u00e7o.<\/p>\n<p>O Walltopia Flex Board \u00e9 um quadro de treinamento inovador projetado para otimizar o uso do espa\u00e7o dispon\u00edvel e, ao mesmo tempo, oferecer uma solu\u00e7\u00e3o de treinamento de alto n\u00edvel. O Flex Board consiste em pain\u00e9is de 1&#215;1 m que podem ser ajustados em qualquer \u00e2ngulo desejado e em uma sele\u00e7\u00e3o especial de suportes e volumes que abrangem uma grande quantidade de pegadas, oferecendo diversas op\u00e7\u00f5es de treinamento.<br \/>\nQuando se trata de economia de espa\u00e7o, o Flex Board pode ser confortavelmente levantado para uma posi\u00e7\u00e3o plana no teto, deixando o espa\u00e7o abaixo para ser&#8230; bem, espa\u00e7o. Os \u00faltimos meses provaram que a utiliza\u00e7\u00e3o do espa\u00e7o \u00e9 igualmente importante quando se trata de treinamento em casa, e a diretoria da Flex est\u00e1 pronta para atender a isso tamb\u00e9m.<\/p>\n<p>A Flex Board \u00e9 f\u00e1cil de ser montada por voc\u00ea mesmo, seguindo um simples manual passo a passo. Ele n\u00e3o requer ferramentas ou t\u00e9cnicos especializados e \u00e9 uma solu\u00e7\u00e3o de treinamento pr\u00e1tica para treinamento em casa ou em academias de escalada.<\/p>\n[\/vc_column_text]<div class=\"link-button-container block width-100 margin-bottom-50 text-align-center\"><a class=\"wt-link \" href=\"http:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027223324\/Walltopia-Training-Boards-Brochure.pdf\" target=\"_blank\">Download Brochure<\/a><\/div>[\/vc_column][\/vc_row][vc_row el_id=&#8221;caixa de for\u00e7a&#8221; css=&#8221;.vc_custom_1637000521473{margin-bottom: 100px !important;}&#8221;][vc_column el_class=&#8221;shadow margin-bottom-100&#8243;][vc_single_image image=&#8221;124452&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][vc_custom_heading text=&#8221;Uma nova dimens\u00e3o no treinamento em casa!&#8221; font_container=&#8221;tag:h4|text_align:center&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1637000807205{margin-top: 20px !important;}&#8221;][vc_row_inner css=&#8221;.vc_custom_1637056695296{margin-bottom: 50px !important;}&#8221;][vc_column_inner width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;124453&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_outline&#8221; css=&#8221;.vc_custom_1637000509307{margin-bottom: 20px !important;}&#8221;][vc_custom_heading text=&#8221;Edi\u00e7\u00e3o b\u00e1sica&#8221; font_container=&#8221;tag:h4|text_align:center|color:%23ffffff&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1637000579735{background-color: #353535 !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1637000684328{margin-top: 20px !important;}&#8221;]\n<ul>\n<li>Estruturas met\u00e1licas, barra de tra\u00e7\u00e3o e 4 pain\u00e9is de madeira compensada<\/li>\n<li>4 unidades de pin\u00e7as<\/li>\n<li>4 unidades de bolsos<\/li>\n<li>2 hemisf\u00e9rios &#8211; 12 cm de di\u00e2metro<\/li>\n<li>12 unidades de grampos de madeira (6 tamanhos x 2 unidades cada)<\/li>\n<li>2 bolas &#8211; 12 cm de di\u00e2metro<\/li>\n<li>2&#215;110 cm de comprimento e cordas de 6 mm &#8211; para prender as bolas \u00e0 barra de eleva\u00e7\u00e3o<\/li>\n<li>Hardware para o corpo principal<\/li>\n<li>Hardware para os suportes e acess\u00f3rios<\/li>\n<li>4-6 unidades de hastes de ancoragem<\/li>\n<li>Chaves hexagonais em forma de L de 6 mm e 8 mm<\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;124454&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_outline&#8221; css=&#8221;.vc_custom_1637000315278{margin-bottom: 20px !important;}&#8221;][vc_custom_heading text=&#8221;Edi\u00e7\u00e3o Butterfly&#8221; font_container=&#8221;tag:h4|text_align:center|color:%23ffffff&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1637000589050{background-color: #353535 !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1637000493333{margin-top: 20px !important;}&#8221;]\n<ul>\n<li>Estruturas met\u00e1licas, barra de tra\u00e7\u00e3o e 4 pain\u00e9is de madeira compensada<\/li>\n<li>4 unidades de pin\u00e7as<\/li>\n<li>Escala de dedos HRT Butterfly<\/li>\n<li>2 hemisf\u00e9rios &#8211; 12 cm de di\u00e2metro<\/li>\n<li>8 unidades de grampos de madeira (6 mm, 8 mm, 10 mm, 15 mm x 2 unidades cada)<\/li>\n<li>2 bolas &#8211; 12 cm de di\u00e2metro<\/li>\n<li>2&#215;110 cm de comprimento e cordas de 6 mm &#8211; para prender as bolas \u00e0 barra de eleva\u00e7\u00e3o<\/li>\n<li>Hardware para o corpo principal<\/li>\n<li>Hardware para os suportes e acess\u00f3rios<\/li>\n<li>4-6 unidades de hastes de ancoragem<\/li>\n<li>Chaves hexagonais em forma de L de 6 mm e 8 mm<\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;124447&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_outline&#8221; css=&#8221;.vc_custom_1637000769561{margin-bottom: 20px !important;}&#8221;][vc_custom_heading text=&#8221;Sistema de polias&#8221; font_container=&#8221;tag:h4|text_align:center|color:%23ffffff&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1637000761123{background-color: #353535 !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1637000753518{margin-top: 20px !important;}&#8221;]<strong>O sistema de polias \u00e9 um complemento opcional, n\u00e3o inclu\u00eddo nos pacotes Basic ou Butterfly.<\/strong><\/p>\n<ul>\n<li>Bra\u00e7o de metal<\/li>\n<li>2 polias<\/li>\n<li>2 maillons<\/li>\n<li>1 parafuso de anel &#8211; M10<\/li>\n<li>4 metros de cabo de 6 mm<\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner css=&#8221;.vc_custom_1637056702912{margin-bottom: 50px !important;}&#8221;]<div class=\"link-button-container block width-100  text-align-center\"><a class=\"wt-link \" href=\"https:\/\/powerbox.hrt-holds.com\/\" target=\"_blank\">Learn More<\/a><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row el_id=&#8221;Piso&#8221;][vc_column][vc_column_text css=&#8221;.vc_custom_1637056942552{margin-bottom: 100px !important;padding-top: 50px !important;padding-right: 50px !important;padding-bottom: 50px !important;padding-left: 50px !important;}&#8221; el_class=&#8221;shdw margin-bottom-100&#8243;]\n<p><strong>A altura m\u00e9dia de uma prancha de treinamento geralmente chega a 3 metros, o que pode ser tratado como uma parede de boulder quando se trata de piso. Nosso parceiro <a href=\"http:\/\/walltopia.com\/more-products\/flooring\/\">Climbat <\/a>recomenda o modelo BM300, adequado para pranchas de treinamento.<\/strong><\/p>\n[\/vc_column_text]<div class=\"info-block-container info-block shdw shdw margin-bottom-100\"><div class=\"content\"><h2>BM 300 Boulder Mat<\/h2><div class=\"full-width-container\"><p><strong>Features:<\/strong><br \/>\n\u2022 Thickness: 300 mm (12``)<br \/>\n\u2022 Multilayer design<br \/>\n\u2022 Overlapping layers technique<br \/>\n\u2022 Good walking stiffness<br \/>\n\u2022 Good energy absorption<br \/>\n\u2022 Recommended max fall height: 4m (13 ft)<br \/>\n\u2022 Compliance with AS 2316.1<\/p>\n<p><strong>Standard Options:<\/strong><br \/>\n\u2022 PVC Vinyl, Modular &amp; One cover<br \/>\n\u2022 Combo Vinyl + Carpet Top, Modular &amp; One cover<\/p>\n<p><strong>Additional Options:<\/strong><br \/>\n\u2022 Higher Fire rating<br \/>\n\u2022 Anti-static cover<\/p>\n<\/div><a href=\"http:\/\/http\" class=\"hover-effect-fast\" target=\"_blank\">More about Climbmat<\/a><\/div><!-- .content --><div id=\"chocolat-parent\" class=\"image\"><a class=\"chocolat-image\" href=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027223139\/training-flooring2-scaled.jpg\"><img decoding=\"async\" src=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027223139\/training-flooring2-800x600.jpg\" width=\"100%\" height=\"auto\" alt=\"\" \/><\/a><\/div><\/div><!-- .info-block-container -->[\/vc_column][\/vc_row][vc_row el_id=&#8221;projetos&#8221;][vc_column]<div class=\"related-projects-container info-block-container info-block shdw carousel-off margin-bottom-100\"><h2 class=\"title\">Our projects<\/h2><div class=\"single-related-project\" style=\"background-image: url(&apos;https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027223344\/training-boards2-800x450.jpg&apos;);\"><a href=\"https:\/\/walltopia.com\/projects\/earth-treks-englewood\/\" class=\"flex-container vertical-align flex-direction-column\"><h3 class=\"item-title\">Earth Treks Englewood<\/h3><p class=\"item-location\">United States of America (USA)<\/p><\/a><\/div><div class=\"single-related-project\" style=\"background-image: url(&apos;https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027230142\/LR_LenaDrapella_RocBloc_251120_9-800x450.jpg&apos;);\"><a href=\"https:\/\/walltopia.com\/projects\/roc-bloc\/\" class=\"flex-container vertical-align flex-direction-column\"><h3 class=\"item-title\">Roc-Bloc<\/h3><p class=\"item-location\">United Kingdom (UK)<\/p><\/a><\/div><div class=\"single-related-project\" style=\"background-image: url(&apos;https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027233323\/SAM_3304-13-800x450.jpg&apos;);\"><a href=\"https:\/\/walltopia.com\/projects\/the-boulder-field\/\" class=\"flex-container vertical-align flex-direction-column\"><h3 class=\"item-title\">The Boulder Field<\/h3><p class=\"item-location\">United States of America (USA)<\/p><\/a><\/div><div class=\"single-related-project\" style=\"background-image: url(&apos;https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231030101033\/Bolder_MichaelTrudeauPhotography-4-1-800x450.jpg&apos;);\"><a href=\"https:\/\/walltopia.com\/projects\/boulder-climbing-community\/\" class=\"flex-container vertical-align flex-direction-column\"><h3 class=\"item-title\">Bolder Climbing Community<\/h3><p class=\"item-location\">Canada<\/p><\/a><\/div><div class=\"single-related-project\" style=\"background-image: url(&apos;https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027223124\/MomentumSS-1-800x450.jpg&apos;);\"><a href=\"https:\/\/walltopia.com\/projects\/momentum-silver-street\/\" class=\"flex-container vertical-align flex-direction-column\"><h3 class=\"item-title\">Momentum Silver Street<\/h3><p class=\"item-location\">United States of America (USA)<\/p><\/a><\/div><div class=\"single-related-project\" style=\"background-image: url(&apos;https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20231027232020\/2020-09-13-11.54.42-26-800x450.jpg&apos;);\"><a href=\"https:\/\/walltopia.com\/projects\/deva-wall\/\" class=\"flex-container vertical-align flex-direction-column\"><h3 class=\"item-title\">Deva Wall<\/h3><p class=\"item-location\">Italy<\/p><\/a><\/div><div class=\"width-100 block float-left text-align-center\"><a href=\"https:\/\/walltopia.com\/pt-br\/projects\/\" class=\"wt-link hover-effect-fast margin-top-25 margin-bottom-25\">See all projects<\/a><\/div><\/div>[\/vc_column][\/vc_row][vc_row el_id=&#8221;downloads&#8221;][vc_column]<div class=\"resources-vc-map full-width-container \"><\/div>[\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"A Walltopia oferece todos os tipos de pranchas de treinamento do mercado com uma estrutura aut\u00f4noma ou montada na parede, totalmente compat\u00edvel com o padr\u00e3o de parede de boulder EN-12572-2","protected":false},"featured_media":174915,"template":"","wall_category":[1149],"class_list":["post-124424","wt_wall_type","type-wt_wall_type","status-publish","has-post-thumbnail","hentry","wall_category-paredes-de-escalada"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Quadros de treinamento | Walltopia<\/title>\n<meta name=\"description\" content=\"A Walltopia oferece todos os tipos de quadros de treinamento do mercado com uma estrutura aut\u00f4noma ou montada na parede, totalmente compat\u00edvel com a norma EN-12572-2.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/walltopia.com\/pt-br\/products\/quadros-de-treinamento\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quadros de treinamento\" \/>\n<meta property=\"og:description\" content=\"A Walltopia oferece todos os tipos de quadros de treinamento do mercado com uma estrutura aut\u00f4noma ou montada na parede, totalmente compat\u00edvel com a norma EN-12572-2.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/walltopia.com\/pt-br\/products\/quadros-de-treinamento\/\" \/>\n<meta property=\"og:site_name\" content=\"Walltopia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/walltopiaclimbing\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-28T08:24:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250722135007\/DSC_5687-6-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1277\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@walltopiabg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/products\\\/quadros-de-treinamento\\\/\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/products\\\/quadros-de-treinamento\\\/\",\"name\":\"Quadros de treinamento | Walltopia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/products\\\/quadros-de-treinamento\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/products\\\/quadros-de-treinamento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20251104165841\\\/quantum-board-m-1.png\",\"datePublished\":\"2021-03-31T16:45:08+00:00\",\"dateModified\":\"2026-01-28T08:24:14+00:00\",\"description\":\"A Walltopia oferece todos os tipos de quadros de treinamento do mercado com uma estrutura aut\u00f4noma ou montada na parede, totalmente compat\u00edvel com a norma EN-12572-2.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/products\\\/quadros-de-treinamento\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/products\\\/quadros-de-treinamento\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/products\\\/quadros-de-treinamento\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20251104165841\\\/quantum-board-m-1.png\",\"contentUrl\":\"https:\\\/\\\/cdn.walltopia.com\\\/wp-content\\\/uploads\\\/20251104165841\\\/quantum-board-m-1.png\",\"width\":1199,\"height\":1313},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/products\\\/quadros-de-treinamento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/inicio-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Walltopia products\",\"item\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/climbing-walls-types\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Quadros de treinamento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/\",\"name\":\"Walltopia\",\"description\":\"World leader in the design and production of climbing walls and active entertainment attractions\",\"publisher\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#organization\",\"name\":\"Walltopia\",\"url\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Walltopia\"},\"image\":{\"@id\":\"https:\\\/\\\/walltopia.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/walltopiaclimbing\\\/\",\"https:\\\/\\\/x.com\\\/walltopiabg\",\"https:\\\/\\\/www.instagram.com\\\/walltopia.active\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/walltopia-ltd.\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/WALLTOPIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Quadros de treinamento | Walltopia","description":"A Walltopia oferece todos os tipos de quadros de treinamento do mercado com uma estrutura aut\u00f4noma ou montada na parede, totalmente compat\u00edvel com a norma EN-12572-2.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/walltopia.com\/pt-br\/products\/quadros-de-treinamento\/","og_locale":"pt_BR","og_type":"article","og_title":"Quadros de treinamento","og_description":"A Walltopia oferece todos os tipos de quadros de treinamento do mercado com uma estrutura aut\u00f4noma ou montada na parede, totalmente compat\u00edvel com a norma EN-12572-2.","og_url":"https:\/\/walltopia.com\/pt-br\/products\/quadros-de-treinamento\/","og_site_name":"Walltopia","article_publisher":"https:\/\/www.facebook.com\/walltopiaclimbing\/","article_modified_time":"2026-01-28T08:24:14+00:00","og_image":[{"width":1920,"height":1277,"url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20250722135007\/DSC_5687-6-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@walltopiabg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/walltopia.com\/pt-br\/products\/quadros-de-treinamento\/","url":"https:\/\/walltopia.com\/pt-br\/products\/quadros-de-treinamento\/","name":"Quadros de treinamento | Walltopia","isPartOf":{"@id":"https:\/\/walltopia.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/walltopia.com\/pt-br\/products\/quadros-de-treinamento\/#primaryimage"},"image":{"@id":"https:\/\/walltopia.com\/pt-br\/products\/quadros-de-treinamento\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20251104165841\/quantum-board-m-1.png","datePublished":"2021-03-31T16:45:08+00:00","dateModified":"2026-01-28T08:24:14+00:00","description":"A Walltopia oferece todos os tipos de quadros de treinamento do mercado com uma estrutura aut\u00f4noma ou montada na parede, totalmente compat\u00edvel com a norma EN-12572-2.","breadcrumb":{"@id":"https:\/\/walltopia.com\/pt-br\/products\/quadros-de-treinamento\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/walltopia.com\/pt-br\/products\/quadros-de-treinamento\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/walltopia.com\/pt-br\/products\/quadros-de-treinamento\/#primaryimage","url":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20251104165841\/quantum-board-m-1.png","contentUrl":"https:\/\/cdn.walltopia.com\/wp-content\/uploads\/20251104165841\/quantum-board-m-1.png","width":1199,"height":1313},{"@type":"BreadcrumbList","@id":"https:\/\/walltopia.com\/pt-br\/products\/quadros-de-treinamento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/walltopia.com\/pt-br\/inicio-pt\/"},{"@type":"ListItem","position":2,"name":"Walltopia products","item":"https:\/\/walltopia.com\/pt-br\/climbing-walls-types\/"},{"@type":"ListItem","position":3,"name":"Quadros de treinamento"}]},{"@type":"WebSite","@id":"https:\/\/walltopia.com\/pt-br\/#website","url":"https:\/\/walltopia.com\/pt-br\/","name":"Walltopia","description":"World leader in the design and production of climbing walls and active entertainment attractions","publisher":{"@id":"https:\/\/walltopia.com\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/walltopia.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/walltopia.com\/pt-br\/#organization","name":"Walltopia","url":"https:\/\/walltopia.com\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/walltopia.com\/pt-br\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Walltopia"},"image":{"@id":"https:\/\/walltopia.com\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/walltopiaclimbing\/","https:\/\/x.com\/walltopiabg","https:\/\/www.instagram.com\/walltopia.active\/","https:\/\/www.linkedin.com\/company\/walltopia-ltd.","https:\/\/www.youtube.com\/user\/WALLTOPIA"]}]}},"_links":{"self":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/wt_wall_type\/124424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/wt_wall_type"}],"about":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/types\/wt_wall_type"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/media\/174915"}],"wp:attachment":[{"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/media?parent=124424"}],"wp:term":[{"taxonomy":"wall_category","embeddable":true,"href":"https:\/\/walltopia.com\/pt-br\/wp-json\/wp\/v2\/wall_category?post=124424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}